{"id":12687,"date":"2023-05-03T11:30:45","date_gmt":"2023-05-03T09:30:45","guid":{"rendered":"https:\/\/annette-ahrens.at\/onlineshop\/?post_type=product&#038;p=12687"},"modified":"2024-06-15T20:26:10","modified_gmt":"2024-06-15T18:26:10","slug":"dreiflammiger-art-deco-kerzenleuchter-wien-um-1930","status":"publish","type":"product","link":"https:\/\/annette-ahrens.at\/onlineshop\/produkt\/dreiflammiger-art-deco-kerzenleuchter-wien-um-1930\/","title":{"rendered":"Dreiflammiger Art Deco Kerzenleuchter, Wien, um 1930"},"content":{"rendered":"<p>Versilberter dreiflammiger Art Deco Kerzenleuchter<\/p>\n<p>Wien, um 1930<\/p>\n<p>Silber, Hammerschlagdekor, rundes Bein, drei T\u00fcllen mit Tropftassen, gemarkt mit Wiener Beschauzeichen, Meisterzeichen V x H, handpolierter Zustand<\/p>\n<p>H 16 cm<\/p>\n<p>L \u00a024 cm<\/p>\n<p>455 g<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Versilberter dreiflammiger Art Deco Kerzenleuchter Wien, um 1930 Silber, Hammerschlagdekor, rundes Bein, drei T\u00fcllen mit Tropftassen, gemarkt mit Wiener Beschauzeichen, Meisterzeichen V x H, handpolierter Zustand H 16 cm L \u00a024 cm 455 g<\/p>\n","protected":false},"featured_media":21727,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[32,291,278,48,28,132,131,53,26],"product_tag":[],"class_list":{"0":"post-12687","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-festefeiern","7":"product_cat-hochzeit","8":"product_cat-kerzenleuchter-tafeldekorationen","9":"product_cat-kerzenleuchter","10":"product_cat-licht-rauch","11":"product_cat-silber","12":"product_cat-tafeldekorationen","13":"product_cat-weihnachten","14":"product_cat-wiener-melange","16":"first","17":"instock","18":"sold-individually","19":"purchasable","20":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v15.8.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dreiflammiger Art Deco Kerzenleuchter, Wien, um 1930<\/title>\n<meta name=\"description\" content=\"Dreiflammiger Art Deco Kerzenleuchter, Wien, um 1930 \u2665 Antiquit\u00e4ten Online kaufen \u2713 Sichere Lieferung \u2713\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/annette-ahrens.at\/onlineshop\/produkt\/dreiflammiger-art-deco-kerzenleuchter-wien-um-1930\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dreiflammiger Art Deco Kerzenleuchter, Wien, um 1930\" \/>\n<meta property=\"og:description\" content=\"Dreiflammiger Art Deco Kerzenleuchter, Wien, um 1930 \u2665 Antiquit\u00e4ten Online kaufen \u2713 Sichere Lieferung \u2713\" \/>\n<meta property=\"og:url\" content=\"https:\/\/annette-ahrens.at\/onlineshop\/produkt\/dreiflammiger-art-deco-kerzenleuchter-wien-um-1930\/\" \/>\n<meta property=\"og:site_name\" content=\"Tafelkultur Onlineshop\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AnnetteAhrensTafelkultur\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-15T18:26:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/annette-ahrens.at\/onlineshop\/wp-content\/uploads\/2023\/04\/IMG_2899-rotated.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1936\" \/>\n\t<meta property=\"og:image:height\" content=\"1936\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\">\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/annette-ahrens.at\/onlineshop\/#\/schema\/person\/3e19676faae246bba0cb3b7e15f427d8\",\"name\":\"Annette Ahrens\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/annette-ahrens.at\/onlineshop\/#personlogo\",\"inLanguage\":\"de\",\"url\":\"https:\/\/annette-ahrens.at\/onlineshop\/wp-content\/uploads\/2020\/04\/aa_logo_End.png\",\"width\":800,\"height\":164,\"caption\":\"Annette Ahrens\"},\"logo\":{\"@id\":\"https:\/\/annette-ahrens.at\/onlineshop\/#personlogo\"},\"sameAs\":[\"https:\/\/annette-ahrens.at\",\"https:\/\/www.facebook.com\/AnnetteAhrensTafelkultur\",\"https:\/\/www.instagram.com\/tafelkulturistin\/\",\"https:\/\/de.wikipedia.org\/wiki\/Annette_Ahrens\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/annette-ahrens.at\/onlineshop\/#website\",\"url\":\"https:\/\/annette-ahrens.at\/onlineshop\/\",\"name\":\"Tafelkultur Onlineshop\",\"description\":\"Annette Ahrens\",\"publisher\":{\"@id\":\"https:\/\/annette-ahrens.at\/onlineshop\/#\/schema\/person\/3e19676faae246bba0cb3b7e15f427d8\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/annette-ahrens.at\/onlineshop\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/annette-ahrens.at\/onlineshop\/produkt\/dreiflammiger-art-deco-kerzenleuchter-wien-um-1930\/#primaryimage\",\"inLanguage\":\"de\",\"url\":\"https:\/\/annette-ahrens.at\/onlineshop\/wp-content\/uploads\/2023\/04\/IMG_2899-rotated.jpeg\",\"width\":1936,\"height\":1936,\"caption\":\"kerzenleuchter_silber\"},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\/\/annette-ahrens.at\/onlineshop\/produkt\/dreiflammiger-art-deco-kerzenleuchter-wien-um-1930\/#webpage\",\"url\":\"https:\/\/annette-ahrens.at\/onlineshop\/produkt\/dreiflammiger-art-deco-kerzenleuchter-wien-um-1930\/\",\"name\":\"Dreiflammiger Art Deco Kerzenleuchter, Wien, um 1930\",\"isPartOf\":{\"@id\":\"https:\/\/annette-ahrens.at\/onlineshop\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/annette-ahrens.at\/onlineshop\/produkt\/dreiflammiger-art-deco-kerzenleuchter-wien-um-1930\/#primaryimage\"},\"datePublished\":\"2023-05-03T09:30:45+00:00\",\"dateModified\":\"2024-06-15T18:26:10+00:00\",\"description\":\"Dreiflammiger Art Deco Kerzenleuchter, Wien, um 1930 \\u2665 Antiquit\\u00e4ten Online kaufen \\u2713 Sichere Lieferung \\u2713\",\"breadcrumb\":{\"@id\":\"https:\/\/annette-ahrens.at\/onlineshop\/produkt\/dreiflammiger-art-deco-kerzenleuchter-wien-um-1930\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/annette-ahrens.at\/onlineshop\/produkt\/dreiflammiger-art-deco-kerzenleuchter-wien-um-1930\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/annette-ahrens.at\/onlineshop\/produkt\/dreiflammiger-art-deco-kerzenleuchter-wien-um-1930\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/annette-ahrens.at\/onlineshop\/\",\"url\":\"https:\/\/annette-ahrens.at\/onlineshop\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/annette-ahrens.at\/onlineshop\/alle-tafelkultur-objekte\/\",\"url\":\"https:\/\/annette-ahrens.at\/onlineshop\/alle-tafelkultur-objekte\/\",\"name\":\"Alle Tafelkultur Objekte\"}},{\"@type\":\"ListItem\",\"position\":3,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/annette-ahrens.at\/onlineshop\/produkt\/dreiflammiger-art-deco-kerzenleuchter-wien-um-1930\/\",\"url\":\"https:\/\/annette-ahrens.at\/onlineshop\/produkt\/dreiflammiger-art-deco-kerzenleuchter-wien-um-1930\/\",\"name\":\"Dreiflammiger Art Deco Kerzenleuchter, Wien, um 1930\"}}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","_links":{"self":[{"href":"https:\/\/annette-ahrens.at\/onlineshop\/wp-json\/wp\/v2\/product\/12687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/annette-ahrens.at\/onlineshop\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/annette-ahrens.at\/onlineshop\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/annette-ahrens.at\/onlineshop\/wp-json\/wp\/v2\/comments?post=12687"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/annette-ahrens.at\/onlineshop\/wp-json\/wp\/v2\/media\/21727"}],"wp:attachment":[{"href":"https:\/\/annette-ahrens.at\/onlineshop\/wp-json\/wp\/v2\/media?parent=12687"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/annette-ahrens.at\/onlineshop\/wp-json\/wp\/v2\/product_brand?post=12687"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/annette-ahrens.at\/onlineshop\/wp-json\/wp\/v2\/product_cat?post=12687"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/annette-ahrens.at\/onlineshop\/wp-json\/wp\/v2\/product_tag?post=12687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}